{"id":11000,"date":"2015-10-20T18:25:17","date_gmt":"2015-10-20T16:25:17","guid":{"rendered":"http:\/\/www.gruppopdregionetoscana.it\/web\/?p=11000"},"modified":"2015-11-23T15:18:47","modified_gmt":"2015-11-23T14:18:47","slug":"san-marcello-piteglio-ok-iter-per-la-fusione-dei-comuni-niccolai-e-baldi-pd-passaggio-dirimente-per-il-futuro-della-montagna-pistoiese","status":"publish","type":"post","link":"https:\/\/www.gruppopdregionetoscana.it\/web\/san-marcello-piteglio-ok-iter-per-la-fusione-dei-comuni-niccolai-e-baldi-pd-passaggio-dirimente-per-il-futuro-della-montagna-pistoiese\/","title":{"rendered":"San Marcello &#8211; Piteglio, ok iter per la fusione dei Comuni. Niccolai e Baldi (Pd): \u201cPassaggio dirimente per il futuro della Montagna Pistoiese\u201d"},"content":{"rendered":"<p><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-11001\" src=\"http:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2015\/10\/san-marcello-pistoiese.jpg\" alt=\"san marcello pistoiese\" width=\"325\" height=\"244\" srcset=\"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2015\/10\/san-marcello-pistoiese.jpg 500w, https:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2015\/10\/san-marcello-pistoiese-300x225.jpg 300w\" sizes=\"auto, (max-width: 325px) 100vw, 325px\" \/>Il Consiglio regionale approva la proposta di legge che d\u00e0 via\u00a0all&#8217;iter\u00a0referendario per la fusione dei Comuni della\u00a0Montagna pistoiese.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Comincerei a chiamarlo \u2018obiettivo 2017\u2019 quello ci poniamo per il futuro della \u2018Montagna Pistoiese\u2019. La vittoria del si al referendum comporterebbe infatti che, dal 1 gennaio 2017, si passi dagli attuali quattro a due soli Comuni&#8221;, dichiara intervenendo in aula il consigliere regionale,\u00a0<strong>Marco Niccolai<\/strong>.<\/p>\n<p>&#8220;Abbiamo approvato due proposte di fusione fortemente volute e condivise dalle amministrazioni locali coinvolte, e questo \u00e8 un elemento essenziale per la vittoria dei referendum. Ora la parola spetta ai cittadini; da parte nostra non possiamo che continuare a lavorare per un risultato positivo. Anche nella scorsa legislatura, il Consiglio regionale ha trattato pi\u00f9 volte il tema della riorganizzazione senza, per\u00f2, arrivare a nessuna decisione conclusiva. Oggi, con l\u2019approvazione della formulazione del quesito, riusciamo a portare a compimento una discussione che va avanti da anni, perch\u00e9 noi non dobbiamo solo discutere, dobbiamo concretizzare: ora lo facciamo. Vogliamo realizzare una forma di semplificazione istituzionale dell\u2019area montana in modo fortemente condiviso; un aspetto fondamentale anche per lo sviluppo e rilancio economico della stessa. Inoltre, dare vita ai due Comuni, non pregiudica in futuro ulteriori forme di integrazione, qualora ne maturino le condizioni; certo pi\u00f9 facili da realizzarsi partendo dai due Comuni, frutto di fusione, anzich\u00e9 dagli attuali quattro&#8221;.<\/p>\n<p>&#8220;Fare presto e bene le cose che servono e che i cittadini aspettano da un decennio&#8221; &#8211; ha commentato <strong>Massimo Baldi<\/strong>, consigliere regionale Pd e firmatario con Niccolai della proposta di legge per la fusione dei Comuni della Montagna Pistoiese &#8211; Con il voto di oggi in Consiglio regionale, diamo un segno di cambiamento di passo e, allo stesso tempo, un contributo importante nella modernizzazione e semplificazione del sistema istituzionale nella provincia di Pistoia&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Consiglio regionale approva la proposta di legge che d\u00e0 via\u00a0all&#8217;iter\u00a0referendario per la fusione dei Comuni della\u00a0Montagna pistoiese. &nbsp; &#8220;Comincerei a chiamarlo \u2018obiettivo 2017\u2019 quello ci poniamo per il futuro della \u2018Montagna Pistoiese\u2019. La vittoria del si al referendum comporterebbe infatti che, dal 1 gennaio 2017, si passi dagli attuali quattro a due soli Comuni&#8221;, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11001,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[30,969,959,1],"tags":[1121,686,1120,379,1079,1078],"class_list":{"0":"post-11000","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-comunicati-stampa","8":"category-marco-niccolai","9":"category-massimo-baldi","10":"category-proposte-di-legge","11":"tag-appennino","12":"tag-comuni","13":"tag-fusiione","14":"tag-montagna","15":"tag-piteglio","16":"tag-san-marcello-pistoiese","17":"czr-hentry"},"jetpack_featured_media_url":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2015\/10\/san-marcello-pistoiese.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/posts\/11000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/comments?post=11000"}],"version-history":[{"count":0,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/posts\/11000\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/media\/11001"}],"wp:attachment":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/media?parent=11000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/categories?post=11000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/tags?post=11000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}