{"id":12265,"date":"2016-02-17T17:00:01","date_gmt":"2016-02-17T16:00:01","guid":{"rendered":"http:\/\/www.gruppopdregionetoscana.it\/web\/?p=12265"},"modified":"2016-02-19T10:04:05","modified_gmt":"2016-02-19T09:04:05","slug":"inceneritore-di-montale-baldi-e-niccolai-pd-ancora-una-volta-i-5stelle-preferiscono-lo-show-alla-discussione-seria","status":"publish","type":"post","link":"https:\/\/www.gruppopdregionetoscana.it\/web\/inceneritore-di-montale-baldi-e-niccolai-pd-ancora-una-volta-i-5stelle-preferiscono-lo-show-alla-discussione-seria\/","title":{"rendered":"Inceneritore di Montale. Baldi e Niccolai (PD): \u201cAncora una volta i 5stelle preferiscono lo show alla discussione seria\u201d"},"content":{"rendered":"<p>\u201cNella seduta odierna sono state discusse due mozioni sull\u2019inceneritore di Montale, Pistoia, una presentata dal gruppo S\u00ec Toscana e una dal Movimento 5 stelle. Abbiamo chiesto di apportare alcune modifiche e tornare in commissione cos\u00ec da fare sintesi e arrivare ad un testo unico, auspicabilmente condiviso, ma dai Cinque Stelle \u00e8 arrivato un secco no.<\/p>\n<p>Si sono opposti alla discussione, preferendo la strumentalizzazione e la propaganda al dibattito nel merito della questione. Siamo amareggiati per come, ancora una volta, i consiglieri pentastellati non abbiano perso l\u2019occasione di fare show anzich\u00e9 lavorare per il bene dei cittadini toscani.<br \/>\nSono perfettamente in sintonia con la linea nazionale, non ci hanno risparmiato neanche in Consiglio regionale, il teatrino che il Movimento ha messo in scena in Parlamento nelle ultime ore.<\/p>\n<p>Lasciando gli show ai Cinque Stelle, noi abbiamo fatto invece proposte concrete nel nostro testo emendativo alla mozione presentata da S\u00ec Toscana: impegniamo la giunta a riferire al Consiglio Regionale sui lavori del tavolo organizzato dall\u2019assessore Fratoni con i Comuni proprietari dell\u2019impianto, ARPAT, Ladurner, Cis Spa , ASL ed il Sindaco di Montemurlo e sullo stato della procedura in corso sulla verifica dello stato dei terreni sui quali insiste la discarica delle ceneri, al fine di stabilire se vi sia o meno una necessit\u00e0 di eventuali interventi di bonifica; ad attivarsi per una rapida conclusione dei risultati dell\u2019analisi epidemiologica sulla cittadinanza integrando lo strudio con le proposte di ISPO.<\/p>\n<p>Noi abbiamo preso un impegno con i nostri elettori e intendiamo rispettarlo, \u00e8 dall\u2019attivit\u00e0 quotidiana dell\u2019assemblea che si vede la differenza tra chi lavora per raggiungere risultati concreti e chi si diverte a fare spettacolo\u201d. Cos\u00ec Massimo Baldi e Marco Niccolai, consiglieri PD.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cNella seduta odierna sono state discusse due mozioni sull\u2019inceneritore di Montale, Pistoia, una presentata dal gruppo S\u00ec Toscana e una dal Movimento 5 stelle. Abbiamo chiesto di apportare alcune modifiche e tornare in commissione cos\u00ec da fare sintesi e arrivare ad un testo unico, auspicabilmente condiviso, ma dai Cinque Stelle \u00e8 arrivato un secco no. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12266,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[969,959],"tags":[],"class_list":{"0":"post-12265","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-marco-niccolai","8":"category-massimo-baldi","9":"czr-hentry"},"jetpack_featured_media_url":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2016\/02\/baldi-niccolai-669x272.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/posts\/12265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/comments?post=12265"}],"version-history":[{"count":0,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/posts\/12265\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/media\/12266"}],"wp:attachment":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/media?parent=12265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/categories?post=12265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/tags?post=12265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}