{"id":14554,"date":"2016-11-17T17:56:05","date_gmt":"2016-11-17T16:56:05","guid":{"rendered":"http:\/\/www.gruppopdregionetoscana.it\/web\/?p=14554"},"modified":"2016-11-17T17:56:05","modified_gmt":"2016-11-17T16:56:05","slug":"turismo-la-nuova-normativa-toscana-al-centro-dellincontro-con-bugliani-e-ciuoffo","status":"publish","type":"post","link":"https:\/\/www.gruppopdregionetoscana.it\/web\/turismo-la-nuova-normativa-toscana-al-centro-dellincontro-con-bugliani-e-ciuoffo\/","title":{"rendered":"Turismo, la nuova normativa toscana al centro dell\u2019incontro con Bugliani e Ciuoffo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-14555 alignleft\" src=\"http:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2016\/11\/IMG-20161117-WA0015-300x225.jpg\" alt=\"img-20161117-wa0015\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2016\/11\/IMG-20161117-WA0015-300x225.jpg 300w, https:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2016\/11\/IMG-20161117-WA0015-1024x768.jpg 1024w, https:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2016\/11\/IMG-20161117-WA0015.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Regolamentazione della locazione turistica e delle strutture ricettive di vario genere, valorizzazione dell\u2019immagine unitaria del sistema turistico regionale in ogni sua parte, rafforzamento dell\u2019offerta attraverso il sostegno all\u2019innovazione tecnologica e la qualificazione degli operatori e dei servizi, accessibilit\u00e0 e sostenibilit\u00e0. Sono soltanto alcuni dei punti pi\u00f9 importanti inseriti nella proposta di legge che riscrive il Testo unico regionale in materia di turismo, che presto approder\u00e0 sui banchi dell\u2019assemblea toscana. Ne hanno discusso oggi\u00a0<strong>Giacomo Bugliani<\/strong>, consigliere regionale Pd e presidente commissione Affari Istituzionali,\u00a0\u00a0e\u00a0<strong>Stefano Ciuoffo<\/strong>, assessore regionale al Turismo, nel dibattito promosso dal gruppo consiliare Pd in Regione\u00a0<strong>\u201cSi scrive Toscana, si legge Turismo\u201d<\/strong>\u00a0svoltosi a Villa della Rinchiostra a Massa.<\/p>\n<p>\u201cRegolamentare il turismo, aggiornando la normativa esistente significa offrire basi certe e chiare a un settore trainante dell\u2019economia locale e regionale, consentendo di farlo diventare una delle principali leve della ripresa. \u2013 ha introdotto\u00a0<strong>Bugliani<\/strong>\u00a0\u2013 Vogliamo mettere nero su bianco il ruolo strategico del turismo per uno sviluppo economico sostenibile, la promozione e la valorizzazione del territorio. Per poterlo fare era opportuno chiarire le modalit\u00e0 di governance di questo ambito, azione che gi\u00e0 avevamo intrapreso con il riordino delle funzioni provinciali che la Toscana ha realizzato tra le prime a livello nazionale e che ora viene definito in modo organico e preciso. Non solo: vengono affrontate le questioni relative ai diversi generi di strutture ricettive, come era necessario e urgente fare per adeguarsi alle trasformazioni dell\u2019offerta avvenute negli ultimi anni. Obiettivo cruciale poi \u00e8 senza dubbio quello di guardare alla Toscana nel suo insieme, valorizzando non solo le mete pi\u00f9 scontate ma facendo conoscere nella sua interezza il territorio. Penso alla nostra provincia, all\u2019importanza del turismo balneare e nello stesso tempo alle bellezze da scoprire nei nostri piccoli borghi: un impegno da parte di tutti deve essere quello di lavorare per promuovere un\u2019offerta a tutto tondo e attirare cos\u00ec visitatori su tutto il territorio, da Marina di Massa alla Lunigiana. Turismo vuol dire crescita ed \u00e8 significativo e importante il modello di sviluppo che la nuova normativa vuole proporre\u201d.<\/p>\n<p>\u201cIl riordino e l\u2019aggiornamento della normativa in questo settore \u00e8 una grande occasione che va colta con le sue opportunit\u00e0. \u2013 ha illustrato\u00a0<strong>Ciuoffo<\/strong>\u00a0&#8211; Per la Toscana il turismo \u00e8 uno dei motori dello sviluppo; pertanto\u00a0\u00a0la proposta di legge approvata in Giunta e ora all\u2019esame del Consiglio regionale \u00e8 il tentativo di costruire, attraverso il confronto con categorie, enti locali e operatori, una sintesi che costituisca il telaio nuovo nel quale questo sistema cos\u00ec complesso come il turismo possa trovare una sua collocazione che porti a un progetto. Non \u00e8 l\u2019intento di fare l\u2019ennesimo quadro disciplinare, anche se la legge attuale vecchia di 16 anni parla a un mondo che oggettivamente non c\u2019\u00e8 pi\u00f9, ma quello di ridisegnare il contesto per trovare un nuovo equilibrio a vantaggio di operatori e consumatori. Il percorso di ascolto fatto e che stiamo facendo sui territori per avere riscontri o sollecitazioni trover\u00e0 nell\u2019ulteriore confronto in Consiglio Regionale la sintesi adeguata\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Regolamentazione della locazione turistica e delle strutture ricettive di vario genere, valorizzazione dell\u2019immagine unitaria del sistema turistico regionale in ogni sua parte, rafforzamento dell\u2019offerta attraverso il sostegno all\u2019innovazione tecnologica e la qualificazione degli operatori e dei servizi, accessibilit\u00e0 e sostenibilit\u00e0. Sono soltanto alcuni dei punti pi\u00f9 importanti inseriti nella proposta di legge che riscrive il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14555,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[30,961],"tags":[270,147],"class_list":{"0":"post-14554","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-comunicati-stampa","8":"category-giacomo-bugliani","9":"tag-massa","10":"tag-turismo","11":"czr-hentry"},"jetpack_featured_media_url":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2016\/11\/IMG-20161117-WA0015.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/posts\/14554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/comments?post=14554"}],"version-history":[{"count":0,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/posts\/14554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/media\/14555"}],"wp:attachment":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/media?parent=14554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/categories?post=14554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/tags?post=14554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}