{"id":20575,"date":"2021-09-14T18:57:00","date_gmt":"2021-09-14T16:57:00","guid":{"rendered":"https:\/\/www.gruppopdregionetoscana.it\/web\/?p=20575"},"modified":"2021-09-24T10:59:13","modified_gmt":"2021-09-24T08:59:13","slug":"rifiuti-de-robertis-piano-grande-opportunita-per-la-toscana-autosufficienza-e-contenimento-delle-tariffe","status":"publish","type":"post","link":"https:\/\/www.gruppopdregionetoscana.it\/web\/rifiuti-de-robertis-piano-grande-opportunita-per-la-toscana-autosufficienza-e-contenimento-delle-tariffe\/","title":{"rendered":"Rifiuti, De Robertis: &#8220;Piano grande opportunit\u00e0 per la Toscana, autosufficienza e contenimento delle tariffe&#8221;"},"content":{"rendered":"\n<p><strong>\u00a0<\/strong><\/p>\n<p><em>La Presidente della Commissione Ambiente del Consiglio regionale della Toscana \u00e8 intervenuta in aula nel dibattito sulla comunicazione dell&#8217;Assessora Monni sul Piano dell&#8217;economia circolare.<\/em><\/p>\n<p>\u00a0<\/p>\n<p>&#8220;Nel piano che andremo ad elaborare c\u2019\u00e8 una grande opportunit\u00e0 per la Toscana &#8211; spiega la presidente <strong>Lucia De Robertis<\/strong> &#8211; coniugare la problematica gestione dei rifiuti con la costruzione di un sistema produttivo che abbia nel rifiuto la sua materia prima. Un piano all\u2019insegna della innovazione tecnologica, necessaria perch\u00e9 le scelte che andremo a fare siano davvero sostenibili\u201d.<\/p>\n<p>\u00a0<\/p>\n<p>&#8220;Un piano che &#8211; prosegue De Robertis &#8211; deve cogliere l\u2019opportunit\u00e0 offerta dal PNRR e dai fondi europei, risorse necessarie per raggiungere obiettivi di una\u00a0 raccolta differenziata all\u201980% e del riciclo della materia al 65% entro il 2030, per creare filiere produttive incentrate sui rifiuti come risorsa,\u00a0 per garantire una adeguata dotazione impiantistica, sia per i rifiuti urbani che speciali, prevedendo la presenza di termovalorizzatori soltanto dove indispensabili\u00a0 e privilegiandone\u00a0 la riconversione tecnologica. Un piano che confermi la netta contrariet\u00e0 all\u2019apertura di nuove discariche, favorendo una netta riduzione all\u2019utilizzo di quelle esistenti&#8221;.<\/p>\n<p>\u00a0<\/p>\n<p>&#8220;Abbiamo la consapevolezza &#8211; conclude la consigliera dem aretina &#8211; della necessit\u00e0 di procedere velocemente. Non soltanto per le opportunit\u00e0 delle risorse dell\u2019Europa, e dell\u2019adeguamento ai nuovi obiettivi delle politiche comunitarie. Ma per dare il concreto segnale della svolta che vogliamo dare, anche come testimonianza della capacit\u00e0 della Toscana di rispondere alle sfide che la ripresa pone ai territori, per renderli attrattivi agli investimenti, dunque allo sviluppo. Nella consapevolezza di questa necessit\u00e0 di tempi rapidi, nulla per\u00f2 dovr\u00e0- e non sar\u00e0 \u2013 tolto alle prerogative dell\u2019assemblea legislativa, che sicuramente sapr\u00e0 reggere la sfida dei tempi, svolgendo appieno il proprio ruo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 La Presidente della Commissione Ambiente del Consiglio regionale della Toscana \u00e8 intervenuta in aula nel dibattito sulla comunicazione dell&#8217;Assessora Monni sul Piano dell&#8217;economia circolare. \u00a0 &#8220;Nel piano che andremo ad elaborare c\u2019\u00e8 una grande opportunit\u00e0 per la Toscana &#8211; spiega la presidente Lucia De Robertis &#8211; coniugare la problematica gestione dei rifiuti con la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16860,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[30,633],"tags":[198],"class_list":{"0":"post-20575","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-comunicati-stampa","8":"category-notizie-lucia-de-robertis","9":"tag-rifiuti","10":"czr-hentry"},"jetpack_featured_media_url":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2018\/03\/27993163_1394654883972859_8686202567846992800_o.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/posts\/20575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/comments?post=20575"}],"version-history":[{"count":0,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/posts\/20575\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/media\/16860"}],"wp:attachment":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/media?parent=20575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/categories?post=20575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/tags?post=20575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}