{"id":7128,"date":"2013-11-29T15:25:06","date_gmt":"2013-11-29T14:25:06","guid":{"rendered":"http:\/\/www.gruppopdregionetoscana.it\/web\/?p=7128"},"modified":"2013-12-02T12:09:29","modified_gmt":"2013-12-02T11:09:29","slug":"risorgimento-toscana-dal-consiglio-regionale-un-aiuto-per-far-conoscere-la-storia","status":"publish","type":"post","link":"https:\/\/www.gruppopdregionetoscana.it\/web\/risorgimento-toscana-dal-consiglio-regionale-un-aiuto-per-far-conoscere-la-storia\/","title":{"rendered":"Risorgimento in Toscana, dal Consiglio regionale un aiuto per far conoscere la storia"},"content":{"rendered":"<p><a href=\"http:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2013\/08\/consiglio-regionale.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-4858\" alt=\"consiglio regionale\" src=\"http:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2013\/08\/consiglio-regionale-150x150.jpg\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2013\/08\/consiglio-regionale-150x150.jpg 150w, https:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2013\/08\/consiglio-regionale-66x66.jpg 66w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Valorizzare il fondamentale ruolo svolto dalla Toscana durante il Risorgimento per il raggiungimento dell\u2019Unit\u00e0 nazionale, attraverso il sostegno a specifici interventi finalizzati a promuovere lo studio e la divulgazione degli avvenimenti storici accaduti nel territorio regionale in quel periodo. \u00c8 l\u2019obiettivo della proposta di legge <i>\u201c<\/i><i>Norme per la valorizzazione del ruolo della Toscana nel periodo risorgimentale ai fini del conseguimento dell\u2019Unit\u00e0 nazionale\u201d<\/i>, presentata oggi in Consiglio regionale, a primo firmatario <b>Marco Ruggeri<\/b>, capogruppo Pd e, a seguire, <b>Marta Gazzarri<\/b>, capogruppo Idv e <b>Marco Taradash<\/b>, consigliere Nuovo centrodestra. La proposta di legge prevede l\u2019erogazione di contributi per progetti di valorizzazione di beni culturali e paesaggistici, di ricerca e di divulgazione degli avvenimenti della Toscana risorgimentale, di specifici progetti educativi e didattici per le scuole, nonch\u00e9\u00a0 un sostegno alla pubblicazione di volumi e saggi scientifici sul tema e all\u2019incentivazione del turismo culturale attraverso l\u2019organizzazione di mostre, convegni o itinerari: tali progetti saranno inseriti nel Piano della cultura e saranno riferibili a avvenimenti risorgimentali appositamente individuati dalla Giunta regionale grazie\u00a0 all\u2019apporto di docenti e esperti. Beneficiari dei contributi saranno enti locali o enti pubblici e\u00a0 soggetti privati senza scopo di lucro con una stabile organizzazione operativa in Toscana, con uno statuto o un atto costitutivo in cui sono previste le finalit\u00e0 di promozione e valorizzazione dei valori risorgimentali,\u00a0 e che si occupino di storia del Risorgimento toscano in modo continuativo e documentabile da almeno cinque anni.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cAbbiamo ritenuto opportuno introdurre nell\u2019ordinamento regionale una normativa specifica, volta proprio a diffondere e promuovere iniziative culturali che permettano di far conoscere al meglio il ruolo della Toscana nel processo di unificazione nazionale, tante volte poco conosciuto specialmente dalle giovani generazioni. \u2013 spiega <b>Ruggeri <\/b>\u2013 Scopo di questa legge \u00e8 infatti proprio inserire appositi interventi per progetti culturali mirati a approfondire questo tema\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cLa memoria storica da sempre riveste un ruolo fondamentale per formare l&#8217;identit\u00e0 della Regione. \u2013 commenta <b>Gazzarri <\/b>&#8211; Prendere piena consapevolezza di ci\u00f2 \u00e8 prioritario, ed \u00e8 l&#8217;elemento a mio avviso pi\u00f9 significativo della proposta di legge. Diffondere il patrimonio di valori che hanno reso la Toscana protagonista del Risorgimento \u00e8 un primo importante passo per promuovere un turismo culturale che possa rilanciare la nostra Regione anche dal punto di vista economico\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEsistono in Toscana e anche a Livorno piccoli e coraggiosi nuclei \u2018carbonari\u2019 che continuano a diffondere e a difendere la storia\u00a0 la cultura e la tradizione risorgimentale. \u2013 fa presente <b>Taradash<\/b> &#8211; E&#8217; un lavoro spesso ingrato ma significativo, riceveranno piccoli o piccolissimi aiuti economici, ma almeno con questa legge si riconoscer\u00e0 il valore senza prezzo del loro contributo\u201d.<\/p>\n<p><a href=\"http:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2013\/11\/PDL-RISORGIMENTO.pdf\" target=\"_blank\">Il testo della proposta di legge<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valorizzare il fondamentale ruolo svolto dalla Toscana durante il Risorgimento per il raggiungimento dell\u2019Unit\u00e0 nazionale, attraverso il sostegno a specifici interventi finalizzati a promuovere lo studio e la divulgazione degli avvenimenti storici accaduti nel territorio regionale in quel periodo. \u00c8 l\u2019obiettivo della proposta di legge \u201cNorme per la valorizzazione del ruolo della Toscana nel periodo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4877,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[30,1],"tags":[254,110,779,780],"class_list":{"0":"post-7128","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-comunicati-stampa","8":"category-proposte-di-legge","9":"tag-consiglio-regionale","10":"tag-proposta-di-legge","11":"tag-risorgimento","12":"tag-unita-ditalia","13":"czr-hentry"},"jetpack_featured_media_url":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-content\/uploads\/2013\/08\/consiglio-regionale1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/posts\/7128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/comments?post=7128"}],"version-history":[{"count":0,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/posts\/7128\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/media\/4877"}],"wp:attachment":[{"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/media?parent=7128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/categories?post=7128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gruppopdregionetoscana.it\/web\/wp-json\/wp\/v2\/tags?post=7128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}